{"id":1946,"date":"2022-07-25T12:38:41","date_gmt":"2022-07-25T10:38:41","guid":{"rendered":"https:\/\/wanderhexe.org\/cms\/?p=1946"},"modified":"2022-07-25T12:38:41","modified_gmt":"2022-07-25T10:38:41","slug":"kopf-hoch-das-wird-wieder","status":"publish","type":"post","link":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/","title":{"rendered":"Kopf hoch, das wird wieder"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1947\" src=\"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png\" alt=\"\" width=\"1080\" height=\"1920\" srcset=\"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png 1080w, https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564-169x300.png 169w, https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564-576x1024.png 576w, https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564-768x1365.png 768w, https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564-864x1536.png 864w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><span class=\"JsGRdQ\">So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung gemacht wurde, so ist es in Ordnung f\u00fcr einen Moment dar\u00fcber zu trauern. Doch lasse dich nicht davon einnehmen. Dir wurde nicht alles genommen und du solltest mit dem was dir geblieben ist weiter machen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung gemacht wurde, so ist es in Ordnung f\u00fcr einen Moment dar\u00fcber zu trauern. Doch lasse dich nicht davon einnehmen. Dir wurde nicht alles genommen und du solltest mit dem was [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[73],"tags":[629,14],"class_list":["post-1946","post","type-post","status-publish","format-standard","hentry","category-stories","tag-sich-haengen-lassen","tag-trauer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kopf hoch, das wird wieder - wanderhexe.org<\/title>\n<meta name=\"description\" content=\"So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kopf hoch, das wird wieder - wanderhexe.org\" \/>\n<meta property=\"og:description\" content=\"So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/\" \/>\n<meta property=\"og:site_name\" content=\"wanderhexe.org\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-25T10:38:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png\" \/>\n<meta name=\"author\" content=\"manu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/\"},\"author\":{\"name\":\"manu\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#\\\/schema\\\/person\\\/53e2f660dadd5bbbec7cf94dae747bc1\"},\"headline\":\"Kopf hoch, das wird wieder\",\"datePublished\":\"2022-07-25T10:38:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/\"},\"wordCount\":68,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/03092752-0888-4FD5-A94E-D8AAF5B12564.png\",\"keywords\":[\"sich h\u00e4ngen lassen\",\"trauer\"],\"articleSection\":[\"Stories\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/\",\"url\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/\",\"name\":\"Kopf hoch, das wird wieder - wanderhexe.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/03092752-0888-4FD5-A94E-D8AAF5B12564.png\",\"datePublished\":\"2022-07-25T10:38:41+00:00\",\"description\":\"So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/03092752-0888-4FD5-A94E-D8AAF5B12564.png\",\"contentUrl\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/03092752-0888-4FD5-A94E-D8AAF5B12564.png\",\"width\":1080,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/2022\\\/07\\\/25\\\/kopf-hoch-das-wird-wieder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kopf hoch, das wird wieder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/\",\"name\":\"wanderhexe.org\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#organization\",\"name\":\"wanderhexe.org\",\"url\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/F4106D43-B46E-4645-AA0D-40913D048620.jpeg\",\"contentUrl\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/F4106D43-B46E-4645-AA0D-40913D048620.jpeg\",\"width\":1080,\"height\":1080,\"caption\":\"wanderhexe.org\"},\"image\":{\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/die_wanderhexe\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/#\\\/schema\\\/person\\\/53e2f660dadd5bbbec7cf94dae747bc1\",\"name\":\"manu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baa22eb4b67b5b36e6adcea77d5e70e593d1d4979c9d3961cbba9350de3a2cae?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baa22eb4b67b5b36e6adcea77d5e70e593d1d4979c9d3961cbba9350de3a2cae?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baa22eb4b67b5b36e6adcea77d5e70e593d1d4979c9d3961cbba9350de3a2cae?s=96&d=mm&r=g\",\"caption\":\"manu\"},\"sameAs\":[\"http:\\\/\\\/wanderhexe.org\\\/cms\"],\"url\":\"https:\\\/\\\/wanderhexe.org\\\/cms\\\/author\\\/manu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kopf hoch, das wird wieder - wanderhexe.org","description":"So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/","og_locale":"de_DE","og_type":"article","og_title":"Kopf hoch, das wird wieder - wanderhexe.org","og_description":"So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung","og_url":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/","og_site_name":"wanderhexe.org","article_published_time":"2022-07-25T10:38:41+00:00","og_image":[{"url":"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png","type":"","width":"","height":""}],"author":"manu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#article","isPartOf":{"@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/"},"author":{"name":"manu","@id":"https:\/\/wanderhexe.org\/cms\/#\/schema\/person\/53e2f660dadd5bbbec7cf94dae747bc1"},"headline":"Kopf hoch, das wird wieder","datePublished":"2022-07-25T10:38:41+00:00","mainEntityOfPage":{"@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/"},"wordCount":68,"commentCount":0,"publisher":{"@id":"https:\/\/wanderhexe.org\/cms\/#organization"},"image":{"@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#primaryimage"},"thumbnailUrl":"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png","keywords":["sich h\u00e4ngen lassen","trauer"],"articleSection":["Stories"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/","url":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/","name":"Kopf hoch, das wird wieder - wanderhexe.org","isPartOf":{"@id":"https:\/\/wanderhexe.org\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#primaryimage"},"image":{"@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#primaryimage"},"thumbnailUrl":"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png","datePublished":"2022-07-25T10:38:41+00:00","description":"So hast du dir das nicht vorgestellt?! Das was gestern noch sch\u00f6n war, soll heute vorbei sein? Wenn dir heute ein Strich durch die Rechnung","breadcrumb":{"@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#primaryimage","url":"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png","contentUrl":"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2022\/07\/03092752-0888-4FD5-A94E-D8AAF5B12564.png","width":1080,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/wanderhexe.org\/cms\/2022\/07\/25\/kopf-hoch-das-wird-wieder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wanderhexe.org\/cms\/"},{"@type":"ListItem","position":2,"name":"Kopf hoch, das wird wieder"}]},{"@type":"WebSite","@id":"https:\/\/wanderhexe.org\/cms\/#website","url":"https:\/\/wanderhexe.org\/cms\/","name":"wanderhexe.org","description":"","publisher":{"@id":"https:\/\/wanderhexe.org\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wanderhexe.org\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wanderhexe.org\/cms\/#organization","name":"wanderhexe.org","url":"https:\/\/wanderhexe.org\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wanderhexe.org\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2021\/05\/F4106D43-B46E-4645-AA0D-40913D048620.jpeg","contentUrl":"https:\/\/wanderhexe.org\/cms\/wp-content\/uploads\/2021\/05\/F4106D43-B46E-4645-AA0D-40913D048620.jpeg","width":1080,"height":1080,"caption":"wanderhexe.org"},"image":{"@id":"https:\/\/wanderhexe.org\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/die_wanderhexe\/"]},{"@type":"Person","@id":"https:\/\/wanderhexe.org\/cms\/#\/schema\/person\/53e2f660dadd5bbbec7cf94dae747bc1","name":"manu","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/baa22eb4b67b5b36e6adcea77d5e70e593d1d4979c9d3961cbba9350de3a2cae?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baa22eb4b67b5b36e6adcea77d5e70e593d1d4979c9d3961cbba9350de3a2cae?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baa22eb4b67b5b36e6adcea77d5e70e593d1d4979c9d3961cbba9350de3a2cae?s=96&d=mm&r=g","caption":"manu"},"sameAs":["http:\/\/wanderhexe.org\/cms"],"url":"https:\/\/wanderhexe.org\/cms\/author\/manu\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/posts\/1946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/comments?post=1946"}],"version-history":[{"count":1,"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/posts\/1946\/revisions"}],"predecessor-version":[{"id":1948,"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/posts\/1946\/revisions\/1948"}],"wp:attachment":[{"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/media?parent=1946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/categories?post=1946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wanderhexe.org\/cms\/wp-json\/wp\/v2\/tags?post=1946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}